{"id":12264,"date":"2026-02-05T19:06:11","date_gmt":"2026-02-05T19:06:11","guid":{"rendered":"https:\/\/www.wincocentury.com\/product\/rh-22550-56\/"},"modified":"2026-04-29T11:20:38","modified_gmt":"2026-04-29T11:20:38","slug":"rh-22550-56","status":"publish","type":"product","link":"https:\/\/www.wincocentury.com\/en\/product\/rh-22550-56\/","title":{"rendered":"\u5e73\u5e95\u96fb\u714e\u677f &#8211; Fiesta 22550"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<ul>\n<li>\u53ef\u62c6\u5378\u6d17\u7897\u6a5f\u5b89\u5168\u70e4\u76e4<\/li>\n<li>\u4e0d\u7c98\u5857\u5c64<\/li>\n<li>\u4f7f\u7528\u548c\u64cd\u4f5c\u7c21\u55ae<\/li>\n<li>\u5d4c\u5165\u5f0f\u52a0\u71b1\u5143\u4ef6<\/li>\n<li>\u5feb\u901f\u52a0\u71b1<\/li>\n<li>\u53ef\u8abf\u7bc0\u6eab\u5ea6\u63a7\u5236<\/li>\n<li>\u53ef\u62c6\u5378\u96fb\u7e9c\u548c\u6ef4\u6c34\u76e4<\/li>\n<\/ul>","protected":false},"featured_media":12091,"template":"","meta":{"_acf_changed":false,"_uag_custom_page_level_css":"","site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}}},"product_brand":[203],"product_cat":[202],"product_tag":[],"class_list":["post-12264","product","type-product","status-publish","has-post-thumbnail","product_brand-russell-hobbs","product_cat-grill-electric-griddle","desktop-align-center","tablet-align-center","mobile-align-center","first","instock","shipping-taxable","purchasable","product-type-simple"],"acf":[],"spectra_custom_meta":{"_sku":["RH-22550-56"],"_global_unique_id":["4008496852710"],"_regular_price":["958"],"total_sales":["0"],"_tax_status":["taxable"],"_tax_class":[""],"_manage_stock":["no"],"_backorders":["no"],"_sold_individually":["no"],"_virtual":["no"],"_downloadable":["no"],"_download_limit":["-1"],"_download_expiry":["-1"],"_thumbnail_id":["12091"],"_stock":[null],"_stock_status":["instock"],"_wc_average_rating":["0"],"_wc_review_count":["0"],"_product_version":["10.6.1"],"_price":["958"],"name_eng":["Griddle - Fiesta 22550"],"product_short_description_english":["<ul>\n<li>Removable dishwasher safe griddle plate<\/li>\n<li>Non stick coating<\/li>\n<li>Simple to use and operate<\/li>\n<li>Embedded heating element<\/li>\n<li>Fast heat up<\/li>\n<li>Adjustable temperature control<\/li>\n<li>Removable cable and drip tray<\/li>\n<\/ul>"],"_product_image_gallery":["12059,12060,12061"],"_edit_last":["1"],"search_term":["Russell Hobbs - \u5e73\u5e95\u96fb\u714e\u677f - Fiesta 22550 - RH-22550-56 - rh-22550-56 - Griddle - Fiesta 22550"],"astra_style_timestamp_css":["1787718041"],"_uag_css_file_name":["uag-css-12264.css"],"_uag_page_assets":["a:9:{s:3:\"css\";s:64007:\".uag-blocks-common-selector{z-index:var(--z-index-desktop) !important}@media(max-width: 976px){.uag-blocks-common-selector{z-index:var(--z-index-tablet) !important}}@media(max-width: 767px){.uag-blocks-common-selector{z-index:var(--z-index-mobile) !important}}.uagb-tax-not-available{padding:10px;border:1px solid;text-align:center}.uagb-layout-list .uagb-list-wrap{margin-left:10px}.uagb-taxonomy__outer-wrap{margin-bottom:20px}ul.uagb-taxonomy-list-children{margin-bottom:0}.uagb-tax-link h1,.uagb-tax-link h2,.uagb-tax-link h3,.uagb-tax-link h4,.uagb-tax-link h5,.uagb-tax-link h6{margin-top:unset}.uagb-block-475fb748.uagb-taxonomy__outer-wrap.uagb-layout-grid{display: grid;grid-template-columns: repeat(3, 1fr);grid-column-gap: 20px;grid-row-gap: 20px;}.uagb-block-475fb748.uagb-layout-grid .uagb-taxomony-box{padding-left: 20px;padding-right: 20px;padding-top: 20px;padding-bottom: 20px;grid-column-gap: 20px;background-color: #f5f5f5;text-align: center;box-shadow: 0px 0px   #00000070 ;}.uagb-block-475fb748.uagb-layout-grid .uagb-tax-title{letter-spacing: 0px;color: #3b3b3b;margin-bottom: 5px;}.uagb-block-475fb748.uagb-layout-grid .uagb-tax-link{color: #777777;}.uagb-block-475fb748.uagb-layout-list .uagb-tax-list{list-style: disc;color: #3b3b3b;}.uagb-block-475fb748.uagb-layout-list .uagb-tax-list:hover{color: #3b3b3b;}.uagb-block-475fb748.uagb-layout-list .uagb-tax-link-wrap:hover{color: #3b3b3b;}.uagb-block-475fb748.uagb-layout-list .uagb-tax-list a.uagb-tax-link{color: #3b3b3b;}.uagb-block-475fb748.uagb-layout-list .uagb-tax-list a.uagb-tax-link:hover{color: #3b3b3b;}.uagb-block-475fb748.uagb-layout-list .uagb-tax-list .uagb-tax-link-wrap{margin-bottom: 10px;}.uagb-block-475fb748 .uagb-taxonomy-wrap.uagb-layout-grid{display: grid;grid-template-columns: repeat(3, 1fr);grid-column-gap: 20px;grid-row-gap: 20px;}.uagb-block-475fb748 .uagb-layout-grid .uagb-taxomony-box{padding-left: 20px;padding-right: 20px;padding-top: 20px;padding-bottom: 20px;grid-column-gap: 20px;background-color: #f5f5f5;text-align: center;box-shadow: 0px 0px   #00000070 ;}.uagb-block-475fb748 .uagb-layout-grid .uagb-tax-title{letter-spacing: 0px;color: #3b3b3b;margin-bottom: 5px;}.uagb-block-475fb748 .uagb-layout-grid .uagb-tax-link{color: #777777;}.uagb-block-475fb748 .uagb-layout-list .uagb-tax-list{list-style: disc;color: #3b3b3b;}.uagb-block-475fb748 .uagb-layout-list .uagb-tax-list:hover{color: #3b3b3b;}.uagb-block-475fb748 .uagb-layout-list .uagb-tax-list a.uagb-tax-link{color: #3b3b3b;}.uagb-block-475fb748 .uagb-layout-list .uagb-tax-list a.uagb-tax-link:hover{color: #3b3b3b;}.uagb-block-475fb748 .uagb-layout-list .uagb-tax-list .uagb-tax-link-wrap{margin-bottom: 10px;}.uagb-block-475fb748.uagb-layout-list .uagb-tax-separator:hover{border-top-color: #b2b4b5;}.uagb-block-475fb748 .uagb-taxomony-box{border-top-width: 1px;border-left-width: 1px;border-right-width: 1px;border-bottom-width: 1px;border-top-left-radius: 3px;border-top-right-radius: 3px;border-bottom-left-radius: 3px;border-bottom-right-radius: 3px;border-color: #E0E0E0;border-style: solid;}.uagb-block-475fb748 .uagb-taxomony-box:hover{border-color: #E0E0E0;}@media only screen and (max-width: 976px) {.uagb-block-475fb748.uagb-taxonomy-wrap.uagb-layout-grid{grid-template-columns: repeat(2, 1fr);}.uagb-block-475fb748.uagb-taxonomy__outer-wrap.uagb-layout-grid{grid-template-columns: repeat(2, 1fr);}.uagb-block-475fb748.uagb-layout-grid .uagb-taxomony-box{padding-left: 15px;padding-right: 15px;padding-top: 15px;padding-bottom: 15px;}.uagb-block-475fb748 .uagb-taxomony-box{border-style: solid;border-color: #E0E0E0;}}@media only screen and (max-width: 767px) {.uagb-block-475fb748.uagb-taxonomy__outer-wrap.uagb-layout-grid{grid-template-columns: repeat(1, 1fr);}.uagb-block-475fb748.uagb-layout-grid .uagb-taxomony-box{padding-left: 15px;padding-right: 15px;padding-top: 15px;padding-bottom: 15px;}.uagb-block-475fb748 .uagb-taxomony-box{border-style: solid;border-color: #E0E0E0;}}.uagb-ifb-content>svg *{-webkit-transition:all .2s;-o-transition:all .2s;transition:all .2s}.uagb-ifb-content>svg,.uagb-ifb-content{display:inline-block}.uagb-ifb-content>svg{vertical-align:middle;width:inherit;height:inherit;font-style:initial}.uagb-ifb-content .uagb-ifb-icon-wrap svg{box-sizing:content-box;width:inherit;height:inherit}.uagb-ifb-button-wrapper:empty{display:none}div.uagb-ifb-button-wrapper a.uagb-infobox-cta-link,div.uagb-ifb-cta a.uagb-infobox-cta-link,.entry .entry-content a.uagb-infobox-cta-link,a.uagb-infobox-link-wrap,.entry .entry-content a.uagb-infobox-link-wrap{text-decoration:none;align-items:center}.uagb-infobox-icon-left-title.uagb-infobox-image-valign-middle .uagb-ifb-title-wrap,.uagb-infobox-icon-right-title.uagb-infobox-image-valign-middle .uagb-ifb-title-wrap,.uagb-infobox-image-valign-middle .uagb-ifb-icon-wrap,.uagb-infobox-image-valign-middle .uagb-ifb-image-content,.uagb-infobox-icon-left.uagb-infobox-image-valign-middle .uagb-ifb-content,.uagb-infobox-icon-right.uagb-infobox-image-valign-middle .uagb-ifb-content{-ms-flex-item-align:center;-webkit-align-self:center;align-self:center}.uagb-infobox-icon-left-title.uagb-infobox-image-valign-top .uagb-ifb-title-wrap,.uagb-infobox-icon-right-title.uagb-infobox-image-valign-top .uagb-ifb-title-wrap,.uagb-infobox-image-valign-top .uagb-ifb-icon-wrap,.uagb-infobox-image-valign-top .uagb-ifb-image-content,.uagb-infobox-icon-left.uagb-infobox-image-valign-top .uagb-ifb-content,.uagb-infobox-icon-right.uagb-infobox-image-valign-top .uagb-ifb-content{-webkit-align-self:self-start;align-self:self-start}.uagb-infobox-left{justify-content:flex-start;text-align:left;-webkit-box-pack:start;-ms-flex-pack:start;-webkit-justify-content:flex-start;-moz-box-pack:start}.uagb-infobox-center{justify-content:center;text-align:center;-webkit-box-pack:center;-ms-flex-pack:center;-webkit-justify-content:center;-moz-box-pack:center}.uagb-infobox-right{justify-content:flex-end;text-align:right;-webkit-box-pack:end;-ms-flex-pack:end;-webkit-justify-content:flex-end;-moz-box-pack:end}.uagb-infobox-icon-above-title.uagb-infobox__content-wrap,.uagb-infobox-icon-below-title.uagb-infobox__content-wrap{display:block;width:100%}.uagb-infobox-icon-left-title .uagb-ifb-content>svg,.uagb-infobox-icon-left .uagb-ifb-content>svg{margin-right:10px}.uagb-infobox-icon-right-title .uagb-ifb-content>svg,.uagb-infobox-icon-right .uagb-ifb-content>svg{margin-left:10px}.uagb-infobox-icon-left.uagb-infobox__content-wrap,.uagb-infobox-icon-right.uagb-infobox__content-wrap,.uagb-infobox-icon-left-title .uagb-ifb-left-title-image,.uagb-infobox-icon-right-title .uagb-ifb-right-title-image{display:-webkit-box;display:-ms-flexbox;display:-webkit-flex;display:-moz-box;display:flex;-js-display:flex}.uagb-infobox-icon-left-title .uagb-ifb-left-title-image .uagb-ifb-image-content,.uagb-infobox-icon-right-title .uagb-ifb-right-title-image .uagb-ifb-image-content,.uagb-infobox-icon-left .uagb-ifb-image-content,.uagb-infobox-icon-right .uagb-ifb-image-content{flex-shrink:0;line-height:0}.uagb-infobox-icon-left-title .uagb-ifb-left-title-image .uagb-ifb-title-wrap,.uagb-infobox-icon-right-title .uagb-ifb-right-title-image .uagb-ifb-title-wrap,.uagb-infobox-icon-left .uagb-ifb-content,.uagb-infobox-icon-right .uagb-ifb-content{flex-grow:1}.uagb-infobox-icon-right.uagb-infobox__content-wrap,.uagb-infobox-icon-right-title .uagb-ifb-right-title-image{-webkit-box-pack:end;-ms-flex-pack:end;-webkit-justify-content:flex-end;-moz-box-pack:end;justify-content:flex-end}.uagb-ifb-content img{position:relative;display:inline-block;line-height:0;width:auto;height:auto !important;max-width:100%;border-radius:inherit;-webkit-box-sizing:content-box;-moz-box-sizing:content-box;-webkit-border-radius:inherit}.uagb-infobox-module-link{position:absolute;top:0;right:0;bottom:0;left:0;z-index:4;width:100%;height:100%}.uagb-edit-mode .uagb-infobox-module-link{z-index:2}.uagb-infobox-link-icon-after{margin-right:0;margin-left:5px}.uagb-infobox-link-icon-before{margin-right:5px;margin-left:0}.uagb-infobox-link-icon{-webkit-transition:all 200ms linear;transition:all 200ms linear}.uagb-infobox__content-wrap{box-sizing:border-box;position:relative;width:100%;word-break:break-word;z-index:1}.uagb-ifb-separator{display:inline-block;margin:0;border-top-color:#333;border-top-style:solid;border-top-width:2px;line-height:0}.uagb-ifb-button-wrapper{line-height:1}.uagb-ifb-button-wrapper.uagb-ifb-button-type-text .uagb-infobox-cta-link.wp-block-button__link{background-color:unset;border:none}.uagb-ifb-button-wrapper.uagb-ifb-button-type-text .uagb-infobox-cta-link.wp-block-button__link:hover{background-color:unset;border-color:unset}.uagb-ifb-button-wrapper .uagb-infobox-cta-link{cursor:pointer}.uagb-ifb-button-wrapper .uagb-infobox-cta-link.wp-block-button__link{width:auto}.uagb-ifb-button-wrapper .wp-block-button__link svg,.uagb-ifb-button-wrapper .ast-outline-button svg{fill:currentColor}.uagb-infobox__content-wrap a{-webkit-box-shadow:none;box-shadow:none;text-decoration:none}.uagb-ifb-title-wrap{width:100%}.uagb-ifb-title{margin-block-start:0}.uagb-ifb-title-wrap .uagb-ifb-title-prefix{display:block;padding:0;margin:0}.uagb-infobox__content-wrap.uagb-infobox__content-wrap{position:relative}.uagb-ifb-content{width:100%}.uagb-infobox__content-wrap.uagb-infobox,.uagb-ifb-content,.uagb-ifb-title-wrap,.uagb-ifb-title-prefix *,svg.dashicon.dashicons-upload{z-index:1}a.uagb-infobox-link-wrap{color:inherit}.uagb-ifb-content p:empty{display:none}.uagb-infobox__content-wrap .uagb-ifb-content img{display:inline-block;max-width:100%}.uagb-infobox__content-wrap .uagb-ifb-content svg{display:inline-block}.uagb-infobox__content-wrap .uagb-ifb-icon-wrap,.uagb-infobox-icon-left .uagb-ifb-image-content,.uagb-infobox-icon-right .uagb-ifb-image-content{box-sizing:content-box}.uagb-infobox-cta-link>svg{vertical-align:middle;width:15px;height:15px;font-size:15px}.uagb-infobox-cta-link{display:inline-flex}.block-editor-page #wpwrap .uagb-infobox-cta-link svg,.uagb-infobox-cta-link svg{font-style:normal}.uagb-infobox-icon-left-title .uagb-ifb-icon-wrap,.uagb-infobox-icon-left .uagb-ifb-icon-wrap{margin-right:10px;line-height:0}.uagb-infobox-icon-right-title .uagb-ifb-icon-wrap,.uagb-infobox-icon-right .uagb-ifb-icon-wrap{margin-left:10px;line-height:0}html[dir=rtl] .uagb-infobox-icon-left-title .uagb-ifb-icon-wrap,html[dir=rtl] .uagb-infobox-icon-left .uagb-ifb-icon-wrap{margin-left:10px;line-height:0}html[dir=rtl] .uagb-infobox-icon-right-title .uagb-ifb-icon-wrap,html[dir=rtl] .uagb-infobox-icon-right .uagb-ifb-icon-wrap{margin-right:10px;line-height:0}html[dir=rtl] .uagb-infobox-left{justify-content:flex-end;text-align:right;-webkit-box-pack:end;-ms-flex-pack:end;-webkit-justify-content:flex-end;-moz-box-pack:end}html[dir=rtl] .uagb-infobox-right{justify-content:flex-start;text-align:left;-webkit-box-pack:start;-ms-flex-pack:start;-webkit-justify-content:flex-start;-moz-box-pack:start}.uagb-infobox-icon-left .uagb-ifb-left-right-wrap,.uagb-infobox-icon-right .uagb-ifb-left-right-wrap,.uagb-infobox-icon-left-title .uagb-ifb-left-title-image,.uagb-infobox-icon-right-title .uagb-ifb-right-title-image{display:-webkit-box;display:-ms-flexbox;display:flex}.uagb-infobox-icon-right .uagb-ifb-left-right-wrap,.uagb-infobox-icon-right-title .uagb-ifb-right-title-image{-webkit-box-pack:end;-ms-flex-pack:end;-webkit-justify-content:flex-end;-moz-box-pack:end;justify-content:flex-end}a.uagb-infbox__link-to-all{position:absolute;top:0;left:0;z-index:3;width:100%;height:100%;box-shadow:none;text-decoration:none;-webkit-box-shadow:none}@media only screen and (max-width: 976px){.uagb-infobox-stacked-tablet.uagb-infobox__content-wrap .uagb-ifb-image-content{padding:0;margin-bottom:20px}.uagb-infobox-stacked-tablet.uagb-reverse-order-tablet.uagb-infobox__content-wrap{display:-webkit-inline-box;display:-ms-inline-flexbox;display:-webkit-inline-flex;display:-moz-inline-box;display:inline-flex;flex-direction:column-reverse;-js-display:inline-flex;-webkit-box-orient:vertical;-webkit-box-direction:reverse;-ms-flex-direction:column-reverse;-webkit-flex-direction:column-reverse;-moz-box-orient:vertical;-moz-box-direction:reverse}.uagb-infobox-stacked-tablet.uagb-infobox__content-wrap .uagb-ifb-content,.uagb-infobox-stacked-tablet.uagb-infobox__content-wrap .uagb-ifb-icon-wrap,.uagb-infobox-stacked-tablet.uagb-infobox__content-wrap .uagb-ifb-image-content{display:block;width:100%;text-align:center}.uagb-infobox-stacked-tablet.uagb-infobox__content-wrap .uagb-ifb-icon-wrap,.uagb-infobox-stacked-tablet.uagb-infobox__content-wrap .uagb-ifb-image-content{margin-right:0;margin-left:0}.uagb-infobox-stacked-tablet.uagb-infobox__content-wrap{display:inline-block}.uagb-infobox-icon-left-title.uagb-infobox-stacked-tablet .uagb-ifb-image-content,.uagb-infobox-icon-left-title.uagb-infobox-stacked-tablet .uagb-ifb-icon-wrap,.uagb-infobox-icon-left.uagb-infobox-stacked-tablet .uagb-ifb-image-content,.uagb-infobox-icon-left.uagb-infobox-stacked-tablet .uagb-ifb-icon-wrap{margin-right:0}.uagb-infobox-icon-right-title.uagb-infobox-stacked-tablet .uagb-ifb-image-content,.uagb-infobox-icon-right-title.uagb-infobox-stacked-tablet .uagb-ifb-icon-wrap,.uagb-infobox-icon-right.uagb-infobox-stacked-tablet .uagb-ifb-image-content,.uagb-infobox-icon-right.uagb-infobox-stacked-tablet .uagb-ifb-icon-wrap{margin-left:0}.uagb-infobox-icon-left-title .uagb-ifb-separator{margin:10px 0}}@media screen and (max-width: 767px){.uagb-infobox-stacked-mobile.uagb-infobox__content-wrap{display:inline-block}.uagb-infobox-stacked-mobile.uagb-infobox__content-wrap .uagb-ifb-image-content,.uagb-infobox-stacked-mobile.uagb-infobox__content-wrap .uagb-ifb-icon-wrap{padding:0;margin-bottom:20px;margin-right:0;margin-left:0}.uagb-infobox-stacked-mobile.uagb-infobox__content-wrap.uagb-reverse-order-mobile{display:-webkit-inline-box;display:-ms-inline-flexbox;display:-webkit-inline-flex;display:-moz-inline-box;display:inline-flex;flex-direction:column-reverse;-js-display:inline-flex;-webkit-box-orient:vertical;-webkit-box-direction:reverse;-ms-flex-direction:column-reverse;-webkit-flex-direction:column-reverse;-moz-box-orient:vertical;-moz-box-direction:reverse}.uagb-infobox-stacked-mobile.uagb-infobox__content-wrap .uagb-ifb-image-content,.uagb-infobox-stacked-mobile.uagb-infobox__content-wrap .uagb-ifb-icon-wrap,.uagb-infobox-stacked-mobile.uagb-infobox__content-wrap .uagb-ifb-content{display:block;width:100%;text-align:center}.uagb-infobox-icon-left-title.uagb-infobox-stacked-mobile .uagb-ifb-image-content,.uagb-infobox-icon-left-title.uagb-infobox-stacked-mobile .uagb-ifb-icon-wrap,.uagb-infobox-icon-left.uagb-infobox-stacked-mobile .uagb-ifb-image-content,.uagb-infobox-icon-left.uagb-infobox-stacked-mobile .uagb-ifb-icon-wrap{margin-right:0}.uagb-infobox-icon-right-title.uagb-infobox-stacked-mobile .uagb-ifb-image-content,.uagb-infobox-icon-right-title.uagb-infobox-stacked-mobile .uagb-ifb-icon-wrap,.uagb-infobox-icon-right.uagb-infobox-stacked-mobile .uagb-ifb-image-content,.uagb-infobox-icon-right.uagb-infobox-stacked-mobile .uagb-ifb-icon-wrap{margin-left:0}.uagb-infobox-icon-left-title .uagb-ifb-separator{margin:10px 0}}.uagb-ifb-icon svg{width:inherit;height:inherit;vertical-align:middle}.uagb-ifb-button-icon{height:15px;width:15px;font-size:15px;vertical-align:middle}.uagb-ifb-button-icon svg{height:inherit;width:inherit;display:inline-block}.uagb-ifb-button-icon.uagb-ifb-align-icon-after{float:right}.uagb-ifb-cta-button{display:inline-block}.uagb-disable-link{pointer-events:none}@media only screen and (min-width: 977px){.uagb-infobox-margin-wrapper{display:flex}}.uagb-ifb-content .uagb-ifb-desc p:last-child{margin-bottom:0}html[dir=rtl] .uagb-infobox-icon-left-title .uagb-ifb-content>svg,html[dir=rtl] .uagb-infobox-icon-left .uagb-ifb-content>svg{margin-right:0;margin-left:10px}html[dir=rtl] .uagb-infobox-icon-right-title .uagb-ifb-content>svg,html[dir=rtl] .uagb-infobox-icon-right .uagb-ifb-content>svg{margin-left:0;margin-right:10px}html[dir=rtl] .uagb-infobox-link-icon-after{margin-right:5px;margin-left:0}html[dir=rtl] .uagb-infobox-link-icon-before{margin-right:0;margin-left:5px}html[dir=rtl] .uagb-ifb-button-icon.uagb-ifb-align-icon-after{float:left}.uagb-block-9b51c574 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-9b51c574 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;color: #333;}.uagb-block-9b51c574 .uagb-ifb-icon svg{fill: #333;}.uagb-block-9b51c574.uagb-infobox__content-wrap .uagb-ifb-icon-wrap svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-9b51c574 .uagb-ifb-content .uagb-ifb-icon-wrap svg{line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-9b51c574 .uagb-iconbox-icon-wrap{margin: auto;display: inline-flex;align-items: center;justify-content: center;box-sizing: content-box;width: 30px;height: 30px;line-height: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-9b51c574.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-9b51c574.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-9b51c574 .uagb-ifb-content .uagb-ifb-left-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-9b51c574 .uagb-ifb-content .uagb-ifb-right-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-9b51c574 .uagb-infobox__content-wrap .uagb-ifb-imgicon-wrap{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-9b51c574 .uagb-infobox .uagb-ifb-image-content img{border-radius: 0px;}.uagb-block-9b51c574.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-9b51c574.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-9b51c574.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-9b51c574.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-9b51c574 .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 10px;margin-top: 5px;}.uagb-block-9b51c574 .uagb-ifb-title{margin-bottom: 10px;}.uagb-block-9b51c574 .uagb-ifb-desc{margin-bottom: 20px;}.uagb-block-9b51c574 .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;margin-bottom: 0px;}.uagb-block-9b51c574 .uagb-infobox__content-wrap .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;}.uagb-block-9b51c574 .uagb-ifb-align-icon-after{margin-left: 5px;}.uagb-block-9b51c574 .uagb-ifb-align-icon-before{margin-right: 5px;}.uagb-block-9b51c574.uagb-infobox__content-wrap .uagb-ifb-content svg{box-sizing: content-box;}.uagb-block-9b51c574.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-9b51c574 .uagb-infobox__content-wrap{text-align: center;}.uagb-block-9b51c574.uagb-infobox-icon-above-title{text-align: center;}.uagb-block-9b51c574.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-9b51c574 .uagb-iconbox-icon-wrap{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-9b51c574.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-9b51c574.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-9b51c574.uagb-infobox__content-wrap img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-9b51c574.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-9b51c574.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-9b51c574.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-9b51c574.uagb-infobox__content-wrap{text-align: center;}[dir=rtl] .uagb-block-9b51c574.uagb-infobox-icon-above-title{text-align: center;}[dir=rtl] .uagb-block-9b51c574.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}@media only screen and (max-width: 976px) {.uagb-block-9b51c574.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-9b51c574.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-9b51c574.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-9b51c574 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-9b51c574 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-9b51c574 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-9b51c574 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-9b51c574 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-9b51c574.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-9b51c574.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}}@media only screen and (max-width: 767px) {.uagb-block-9b51c574.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-9b51c574.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-9b51c574 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-9b51c574 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-9b51c574.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-9b51c574 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-9b51c574 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-9b51c574 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-9b51c574.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-9b51c574.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}}.uagb-block-bfbd75e6.uagb-taxonomy__outer-wrap.uagb-layout-grid{display: grid;grid-template-columns: repeat(3, 1fr);grid-column-gap: 20px;grid-row-gap: 20px;}.uagb-block-bfbd75e6.uagb-layout-grid .uagb-taxomony-box{padding-left: 20px;padding-right: 20px;padding-top: 20px;padding-bottom: 20px;grid-column-gap: 20px;background-color: #f5f5f5;text-align: center;box-shadow: 0px 0px   #00000070 ;}.uagb-block-bfbd75e6.uagb-layout-grid .uagb-tax-title{letter-spacing: 0px;color: #3b3b3b;margin-bottom: 5px;}.uagb-block-bfbd75e6.uagb-layout-grid .uagb-tax-link{color: #777777;}.uagb-block-bfbd75e6.uagb-layout-list .uagb-tax-list{list-style: disc;color: #3b3b3b;}.uagb-block-bfbd75e6.uagb-layout-list .uagb-tax-list:hover{color: #3b3b3b;}.uagb-block-bfbd75e6.uagb-layout-list .uagb-tax-link-wrap:hover{color: #3b3b3b;}.uagb-block-bfbd75e6.uagb-layout-list .uagb-tax-list a.uagb-tax-link{color: #3b3b3b;}.uagb-block-bfbd75e6.uagb-layout-list .uagb-tax-list a.uagb-tax-link:hover{color: #3b3b3b;}.uagb-block-bfbd75e6.uagb-layout-list .uagb-tax-list .uagb-tax-link-wrap{margin-bottom: 10px;}.uagb-block-bfbd75e6 .uagb-taxonomy-wrap.uagb-layout-grid{display: grid;grid-template-columns: repeat(3, 1fr);grid-column-gap: 20px;grid-row-gap: 20px;}.uagb-block-bfbd75e6 .uagb-layout-grid .uagb-taxomony-box{padding-left: 20px;padding-right: 20px;padding-top: 20px;padding-bottom: 20px;grid-column-gap: 20px;background-color: #f5f5f5;text-align: center;box-shadow: 0px 0px   #00000070 ;}.uagb-block-bfbd75e6 .uagb-layout-grid .uagb-tax-title{letter-spacing: 0px;color: #3b3b3b;margin-bottom: 5px;}.uagb-block-bfbd75e6 .uagb-layout-grid .uagb-tax-link{color: #777777;}.uagb-block-bfbd75e6 .uagb-layout-list .uagb-tax-list{list-style: disc;color: #3b3b3b;}.uagb-block-bfbd75e6 .uagb-layout-list .uagb-tax-list:hover{color: #3b3b3b;}.uagb-block-bfbd75e6 .uagb-layout-list .uagb-tax-list a.uagb-tax-link{color: #3b3b3b;}.uagb-block-bfbd75e6 .uagb-layout-list .uagb-tax-list a.uagb-tax-link:hover{color: #3b3b3b;}.uagb-block-bfbd75e6 .uagb-layout-list .uagb-tax-list .uagb-tax-link-wrap{margin-bottom: 10px;}.uagb-block-bfbd75e6.uagb-layout-list .uagb-tax-separator:hover{border-top-color: #b2b4b5;}.uagb-block-bfbd75e6 .uagb-taxomony-box{border-top-width: 1px;border-left-width: 1px;border-right-width: 1px;border-bottom-width: 1px;border-top-left-radius: 3px;border-top-right-radius: 3px;border-bottom-left-radius: 3px;border-bottom-right-radius: 3px;border-color: #E0E0E0;border-style: solid;}.uagb-block-bfbd75e6 .uagb-taxomony-box:hover{border-color: #E0E0E0;}@media only screen and (max-width: 976px) {.uagb-block-bfbd75e6.uagb-taxonomy-wrap.uagb-layout-grid{grid-template-columns: repeat(2, 1fr);}.uagb-block-bfbd75e6.uagb-taxonomy__outer-wrap.uagb-layout-grid{grid-template-columns: repeat(2, 1fr);}.uagb-block-bfbd75e6.uagb-layout-grid .uagb-taxomony-box{padding-left: 15px;padding-right: 15px;padding-top: 15px;padding-bottom: 15px;}.uagb-block-bfbd75e6 .uagb-taxomony-box{border-style: solid;border-color: #E0E0E0;}}@media only screen and (max-width: 767px) {.uagb-block-bfbd75e6.uagb-taxonomy__outer-wrap.uagb-layout-grid{grid-template-columns: repeat(1, 1fr);}.uagb-block-bfbd75e6.uagb-layout-grid .uagb-taxomony-box{padding-left: 15px;padding-right: 15px;padding-top: 15px;padding-bottom: 15px;}.uagb-block-bfbd75e6 .uagb-taxomony-box{border-style: solid;border-color: #E0E0E0;}}.wp-block-uagb-advanced-heading h1,.wp-block-uagb-advanced-heading h2,.wp-block-uagb-advanced-heading h3,.wp-block-uagb-advanced-heading h4,.wp-block-uagb-advanced-heading h5,.wp-block-uagb-advanced-heading h6,.wp-block-uagb-advanced-heading p,.wp-block-uagb-advanced-heading div{word-break:break-word}.wp-block-uagb-advanced-heading .uagb-heading-text{margin:0}.wp-block-uagb-advanced-heading .uagb-desc-text{margin:0}.wp-block-uagb-advanced-heading .uagb-separator{font-size:0;border-top-style:solid;display:inline-block;margin:0 0 10px 0}.wp-block-uagb-advanced-heading .uagb-highlight{color:#f78a0c;border:0;transition:all .3s ease}.uag-highlight-toolbar{border-left:0;border-top:0;border-bottom:0;border-radius:0;border-right-color:#1e1e1e}.uag-highlight-toolbar .components-button{border-radius:0;outline:none}.uag-highlight-toolbar .components-button.is-primary{color:#fff}.wp-block-uagb-advanced-heading.uagb-block-8a509230.wp-block-uagb-advanced-heading .uagb-heading-text{color: #ffffff;}.wp-block-uagb-advanced-heading.uagb-block-8a509230.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-8a509230.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-8a509230.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-8a509230.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-80a5668e.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-80a5668e.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-80a5668e.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-80a5668e.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-separator{text-align:center;box-sizing:border-box;line-height:0}.wp-block-uagb-separator__inner{display:inline-block}.wp-block-uagb-separator:not(.wp-block-uagb-separator--text):not(.wp-block-uagb-separator--icon) .wp-block-uagb-separator__inner{border-top-style:solid;-webkit-mask:var(--my-background-image);-webkit-mask-size:38px 100%;-webkit-mask-repeat:repeat-x}.wp-block-uagb-separator--text .wp-block-uagb-separator__inner,.wp-block-uagb-separator--icon .wp-block-uagb-separator__inner{display:flex;justify-content:center;align-items:center;margin:0 auto}.wp-block-uagb-separator--text .wp-block-uagb-separator__inner::before,.wp-block-uagb-separator--icon .wp-block-uagb-separator__inner::before{display:block;content:\"\";border-bottom:0;flex-grow:1;border-top-color:#333;border-top-style:solid;-webkit-mask:var(--my-background-image);-webkit-mask-size:38px 100%;-webkit-mask-repeat:repeat-x}.wp-block-uagb-separator--text .wp-block-uagb-separator__inner::after,.wp-block-uagb-separator--icon .wp-block-uagb-separator__inner::after{display:block;content:\"\";border-bottom:0;flex-grow:1;border-top-color:#333;border-top-style:solid;-webkit-mask:var(--my-background-image);-webkit-mask-size:38px 100%;-webkit-mask-repeat:repeat-x}.wp-block-uagb-separator--icon .wp-block-uagb-separator-element svg{font-size:30px;color:#333;fill:#333;width:30px;height:30px;line-height:30px;max-width:none}.wp-block-uagb-separator--text .wp-block-uagb-separator-element .uagb-html-tag{word-break:initial;margin:0}.uagb-block-02e25341.wp-block-uagb-separator{text-align: left;}.uagb-block-02e25341.wp-block-uagb-separator--text .wp-block-uagb-separator-element .uagb-html-tag{font-style: normal;line-height: 1em;}.uagb-block-02e25341 .uagb-separator-spacing-wrapper{margin-top: 0px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-02e25341.wp-block-uagb-separator:not(.wp-block-uagb-separator--text):not(.wp-block-uagb-separator--icon) .wp-block-uagb-separator__inner{-webkit-mask-size: 5px 100%;border-top-width: 1px;width: 80%;border-top-color: var(--ast-global-color-5);border-top-style: solid;margin-top: 5px;margin-bottom: 5px;}@media only screen and (max-width: 976px) {.uagb-block-02e25341.wp-block-uagb-separator{text-align: center;}.uagb-block-02e25341.wp-block-uagb-separator--text .wp-block-uagb-separator-element .uagb-html-tag{font-style: normal;margin-bottom: initial;line-height: 1em;}.uagb-block-02e25341.wp-block-uagb-separator:not(.wp-block-uagb-separator--text):not(.wp-block-uagb-separator--icon) .wp-block-uagb-separator__inner{-webkit-mask-size: 5px 100%;width: 100%;border-top-color: var(--ast-global-color-5);border-top-style: solid;margin-top: 5px;margin-bottom: 5px;}}@media only screen and (max-width: 767px) {.uagb-block-02e25341.wp-block-uagb-separator{text-align: center;}.uagb-block-02e25341.wp-block-uagb-separator--text .wp-block-uagb-separator-element .uagb-html-tag{font-style: normal;margin-bottom: initial;line-height: 1em;}.uagb-block-02e25341.wp-block-uagb-separator:not(.wp-block-uagb-separator--text):not(.wp-block-uagb-separator--icon) .wp-block-uagb-separator__inner{-webkit-mask-size: 5px 100%;width: 100%;border-top-color: var(--ast-global-color-5);border-top-style: solid;margin-top: 5px;margin-bottom: 5px;}}.wp-block-uagb-advanced-heading.uagb-block-a545db33.wp-block-uagb-advanced-heading {margin-top: 30px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.wp-block-uagb-advanced-heading.uagb-block-a545db33.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-a545db33.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-a545db33.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-a545db33.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}@media only screen and (max-width: 976px) {.wp-block-uagb-advanced-heading.uagb-block-a545db33.wp-block-uagb-advanced-heading {text-align: left;padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;margin-top: 0px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;}.wp-block-uagb-advanced-heading.uagb-block-a545db33 .uagb-heading-text{font-size: 30px;line-height: 0em;}}@media only screen and (max-width: 767px) {.wp-block-uagb-advanced-heading.uagb-block-a545db33.wp-block-uagb-advanced-heading {text-align: center;padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;margin-top: 0px;margin-right: 0px;margin-bottom: 10px;margin-left: 0px;}.wp-block-uagb-advanced-heading.uagb-block-a545db33.wp-block-uagb-advanced-heading .uagb-highlight{padding-bottom: 0px;}.wp-block-uagb-advanced-heading.uagb-block-a545db33 .uagb-heading-text{font-size: 24px;}}.uagb-block-11a491f6 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-11a491f6 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;color: #333;}.uagb-block-11a491f6 .uagb-ifb-icon svg{fill: #333;}.uagb-block-11a491f6.uagb-infobox__content-wrap .uagb-ifb-icon-wrap svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-11a491f6 .uagb-ifb-content .uagb-ifb-icon-wrap svg{line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-11a491f6 .uagb-iconbox-icon-wrap{margin: auto;display: inline-flex;align-items: center;justify-content: center;box-sizing: content-box;width: 30px;height: 30px;line-height: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-11a491f6.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-11a491f6.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-11a491f6 .uagb-ifb-content .uagb-ifb-left-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-11a491f6 .uagb-ifb-content .uagb-ifb-right-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-11a491f6 .uagb-infobox__content-wrap .uagb-ifb-imgicon-wrap{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-11a491f6 .uagb-infobox .uagb-ifb-image-content img{border-radius: 0px;}.uagb-block-11a491f6.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-11a491f6.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-11a491f6.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-11a491f6.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-11a491f6 .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 10px;margin-top: 5px;}.uagb-block-11a491f6 .uagb-ifb-title{margin-bottom: 10px;}.uagb-block-11a491f6 .uagb-ifb-desc{margin-bottom: 20px;}.uagb-block-11a491f6 .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;margin-bottom: 0px;}.uagb-block-11a491f6 .uagb-infobox__content-wrap .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;}.uagb-block-11a491f6 .uagb-ifb-align-icon-after{margin-left: 5px;}.uagb-block-11a491f6 .uagb-ifb-align-icon-before{margin-right: 5px;}.uagb-block-11a491f6.uagb-infobox__content-wrap .uagb-ifb-content svg{box-sizing: content-box;}.uagb-block-11a491f6.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-11a491f6 .uagb-infobox__content-wrap{text-align: center;}.uagb-block-11a491f6.uagb-infobox-icon-above-title{text-align: center;}.uagb-block-11a491f6.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-11a491f6 .uagb-iconbox-icon-wrap{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-11a491f6.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-11a491f6.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-11a491f6.uagb-infobox__content-wrap img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-11a491f6.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-11a491f6.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-11a491f6.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-11a491f6.uagb-infobox__content-wrap{text-align: center;}[dir=rtl] .uagb-block-11a491f6.uagb-infobox-icon-above-title{text-align: center;}[dir=rtl] .uagb-block-11a491f6.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}@media only screen and (max-width: 976px) {.uagb-block-11a491f6.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-11a491f6.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-11a491f6.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-11a491f6 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-11a491f6 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-11a491f6 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-11a491f6 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-11a491f6 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-11a491f6.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-11a491f6.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}}@media only screen and (max-width: 767px) {.uagb-block-11a491f6.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-11a491f6.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-11a491f6 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-11a491f6 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-11a491f6.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-11a491f6 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-11a491f6 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-11a491f6 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-11a491f6.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-11a491f6.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}}.wp-block-uagb-image{display:flex}.wp-block-uagb-image__figure{position:relative;display:flex;flex-direction:column;max-width:100%;height:auto;margin:0}.wp-block-uagb-image__figure img{height:auto;display:flex;max-width:100%;transition:box-shadow .2s ease}.wp-block-uagb-image__figure>a{display:inline-block}.wp-block-uagb-image__figure figcaption{text-align:center;margin-top:.5em;margin-bottom:1em}.wp-block-uagb-image .components-placeholder.block-editor-media-placeholder .components-placeholder__instructions{align-self:center}.wp-block-uagb-image--align-left{text-align:left}.wp-block-uagb-image--align-right{text-align:right}.wp-block-uagb-image--align-center{text-align:center}.wp-block-uagb-image--align-full .wp-block-uagb-image__figure{margin-left:calc(50% - 50vw);margin-right:calc(50% - 50vw);max-width:100vw;width:100vw;height:auto}.wp-block-uagb-image--align-full .wp-block-uagb-image__figure img{height:auto;width:100% !important}.wp-block-uagb-image--align-wide .wp-block-uagb-image__figure img{height:auto;width:100%}.wp-block-uagb-image--layout-overlay__color-wrapper{position:absolute;left:0;top:0;right:0;bottom:0;opacity:.2;background:rgba(0,0,0,.5);transition:opacity .35s ease-in-out}.wp-block-uagb-image--layout-overlay-link{position:absolute;left:0;right:0;bottom:0;top:0}.wp-block-uagb-image--layout-overlay .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{opacity:1}.wp-block-uagb-image--layout-overlay__inner{position:absolute;left:15px;right:15px;bottom:15px;top:15px;display:flex;align-items:center;justify-content:center;flex-direction:column;border-color:#fff;transition:.35s ease-in-out}.wp-block-uagb-image--layout-overlay__inner.top-left,.wp-block-uagb-image--layout-overlay__inner.top-center,.wp-block-uagb-image--layout-overlay__inner.top-right{justify-content:flex-start}.wp-block-uagb-image--layout-overlay__inner.bottom-left,.wp-block-uagb-image--layout-overlay__inner.bottom-center,.wp-block-uagb-image--layout-overlay__inner.bottom-right{justify-content:flex-end}.wp-block-uagb-image--layout-overlay__inner.top-left,.wp-block-uagb-image--layout-overlay__inner.center-left,.wp-block-uagb-image--layout-overlay__inner.bottom-left{align-items:flex-start}.wp-block-uagb-image--layout-overlay__inner.top-right,.wp-block-uagb-image--layout-overlay__inner.center-right,.wp-block-uagb-image--layout-overlay__inner.bottom-right{align-items:flex-end}.wp-block-uagb-image--layout-overlay__inner .uagb-image-heading{color:#fff;transition:transform .35s,opacity .35s ease-in-out;transform:translate3d(0, 24px, 0);margin:0;line-height:1em}.wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{width:30%;border-top-width:2px;border-top-color:#fff;border-top-style:solid;margin-bottom:10px;opacity:0;transition:transform .4s,opacity .4s ease-in-out;transform:translate3d(0, 30px, 0)}.wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity:0;overflow:visible;color:#fff;transition:transform .45s,opacity .45s ease-in-out;transform:translate3d(0, 35px, 0)}.wp-block-uagb-image--layout-overlay__inner:hover .uagb-image-heading,.wp-block-uagb-image--layout-overlay__inner:hover .uagb-image-separator,.wp-block-uagb-image--layout-overlay__inner:hover .uagb-image-caption{opacity:1;transform:translate3d(0, 0, 0)}.wp-block-uagb-image--effect-zoomin .wp-block-uagb-image__figure img,.wp-block-uagb-image--effect-zoomin .wp-block-uagb-image__figure .wp-block-uagb-image--layout-overlay__color-wrapper{transform:scale(1);transition:transform .35s ease-in-out}.wp-block-uagb-image--effect-zoomin .wp-block-uagb-image__figure:hover img,.wp-block-uagb-image--effect-zoomin .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{transform:scale(1.05)}.wp-block-uagb-image--effect-slide .wp-block-uagb-image__figure img,.wp-block-uagb-image--effect-slide .wp-block-uagb-image__figure .wp-block-uagb-image--layout-overlay__color-wrapper{width:calc(100% + 40px) !important;max-width:none !important;transform:translate3d(-40px, 0, 0);transition:transform .35s ease-in-out}.wp-block-uagb-image--effect-slide .wp-block-uagb-image__figure:hover img,.wp-block-uagb-image--effect-slide .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{transform:translate3d(0, 0, 0)}.wp-block-uagb-image--effect-grayscale img{filter:grayscale(0%);transition:.35s ease-in-out}.wp-block-uagb-image--effect-grayscale:hover img{filter:grayscale(100%)}.wp-block-uagb-image--effect-blur img{filter:blur(0);transition:.35s ease-in-out}.wp-block-uagb-image--effect-blur:hover img{filter:blur(3px)}.uagb-block-d068befa.wp-block-uagb-image--layout-default figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-d068befa.wp-block-uagb-image .wp-block-uagb-image__figure figcaption{font-style: normal;align-self: center;}.uagb-block-d068befa.wp-block-uagb-image--layout-overlay figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-d068befa.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 0.2;}.uagb-block-d068befa.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner{left: 15px;right: 15px;top: 15px;bottom: 15px;}.uagb-block-d068befa.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading{font-style: normal;color: #fff;opacity: 1;}.uagb-block-d068befa.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading a{color: #fff;}.uagb-block-d068befa.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 0;}.uagb-block-d068befa.wp-block-uagb-image--layout-overlay .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 1;}.uagb-block-d068befa.wp-block-uagb-image .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{width: 30%;border-top-width: 2px;border-top-color: #fff;opacity: 0;}.uagb-block-d068befa.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}.uagb-block-d068befa.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 1;}.uagb-block-d068befa.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{opacity: 1;}.uagb-block-d068befa.wp-block-uagb-image--layout-default figure:hover img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-d068befa.wp-block-uagb-image--layout-overlay figure:hover img{box-shadow: 0px 0px 0 #00000070;}@media only screen and (max-width: 976px) {.uagb-block-d068befa.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}}@media only screen and (max-width: 767px) {.uagb-block-d068befa.wp-block-uagb-image .wp-block-uagb-image__figure img{width: 119px;height: auto;}}.wp-block-uagb-container{display:flex;position:relative;box-sizing:border-box;transition-property:box-shadow;transition-duration:.2s;transition-timing-function:ease}.wp-block-uagb-container .spectra-container-link-overlay{bottom:0;left:0;position:absolute;right:0;top:0;z-index:10}.wp-block-uagb-container.uagb-is-root-container{margin-left:auto;margin-right:auto}.wp-block-uagb-container.alignfull.uagb-is-root-container .uagb-container-inner-blocks-wrap{display:flex;position:relative;box-sizing:border-box;margin-left:auto !important;margin-right:auto !important}.wp-block-uagb-container .wp-block-uagb-blockquote,.wp-block-uagb-container .wp-block-spectra-pro-login,.wp-block-uagb-container .wp-block-spectra-pro-register{margin:unset}.wp-block-uagb-container .uagb-container__video-wrap{height:100%;width:100%;top:0;left:0;position:absolute;overflow:hidden;-webkit-transition:opacity 1s;-o-transition:opacity 1s;transition:opacity 1s}.wp-block-uagb-container .uagb-container__video-wrap video{max-width:100%;width:100%;height:100%;margin:0;line-height:1;border:none;display:inline-block;vertical-align:baseline;-o-object-fit:cover;object-fit:cover;background-size:cover}.wp-block-uagb-container.uagb-layout-grid{display:grid;width:100%}.wp-block-uagb-container.uagb-layout-grid>.uagb-container-inner-blocks-wrap{display:inherit;width:inherit}.wp-block-uagb-container.uagb-layout-grid>.uagb-container-inner-blocks-wrap>.wp-block-uagb-container{max-width:unset !important;width:unset !important}.wp-block-uagb-container.uagb-layout-grid>.wp-block-uagb-container{max-width:unset !important;width:unset !important}.wp-block-uagb-container.uagb-layout-grid.uagb-is-root-container{margin-left:auto;margin-right:auto}.wp-block-uagb-container.uagb-layout-grid.uagb-is-root-container>.wp-block-uagb-container{max-width:unset !important;width:unset !important}.wp-block-uagb-container.uagb-layout-grid.alignwide.uagb-is-root-container{margin-left:auto;margin-right:auto}.wp-block-uagb-container.uagb-layout-grid.alignfull.uagb-is-root-container .uagb-container-inner-blocks-wrap{display:inherit;position:relative;box-sizing:border-box;margin-left:auto !important;margin-right:auto !important}body .wp-block-uagb-container>.uagb-container-inner-blocks-wrap>*:not(.wp-block-uagb-container):not(.wp-block-uagb-column):not(.wp-block-uagb-container):not(.wp-block-uagb-section):not(.uagb-container__shape):not(.uagb-container__video-wrap):not(.wp-block-spectra-pro-register):not(.wp-block-spectra-pro-login):not(.uagb-slider-container):not(.spectra-image-gallery__control-lightbox):not(.wp-block-uagb-info-box),body .wp-block-uagb-container>.uagb-container-inner-blocks-wrap,body .wp-block-uagb-container>*:not(.wp-block-uagb-container):not(.wp-block-uagb-column):not(.wp-block-uagb-container):not(.wp-block-uagb-section):not(.uagb-container__shape):not(.uagb-container__video-wrap):not(.wp-block-spectra-pro-register):not(.wp-block-spectra-pro-login):not(.uagb-slider-container):not(.spectra-container-link-overlay):not(.spectra-image-gallery__control-lightbox):not(.wp-block-uagb-lottie):not(.uagb-faq__outer-wrap){min-width:unset !important;width:100%;position:relative}body .ast-container .wp-block-uagb-container>.uagb-container-inner-blocks-wrap>.wp-block-uagb-container>ul,body .ast-container .wp-block-uagb-container>.uagb-container-inner-blocks-wrap>.wp-block-uagb-container ol,body .ast-container .wp-block-uagb-container>.uagb-container-inner-blocks-wrap>ul,body .ast-container .wp-block-uagb-container>.uagb-container-inner-blocks-wrap ol{max-width:-webkit-fill-available;margin-block-start:0;margin-block-end:0;margin-left:20px}.ast-plain-container .editor-styles-wrapper .block-editor-block-list__layout.is-root-container .uagb-is-root-container.wp-block-uagb-container.alignwide{margin-left:auto;margin-right:auto}.uagb-container__shape{overflow:hidden;position:absolute;left:0;width:100%;line-height:0;direction:ltr}.uagb-container__shape-top{top:-3px}.uagb-container__shape-bottom{bottom:-3px}.uagb-container__shape.uagb-container__invert.uagb-container__shape-bottom,.uagb-container__shape.uagb-container__invert.uagb-container__shape-top{-webkit-transform:rotate(180deg);-ms-transform:rotate(180deg);transform:rotate(180deg)}.uagb-container__shape.uagb-container__shape-flip svg{transform:translateX(-50%) rotateY(180deg)}.uagb-container__shape svg{display:block;width:-webkit-calc(100% + 1.3px);width:calc(100% + 1.3px);position:relative;left:50%;-webkit-transform:translateX(-50%);-ms-transform:translateX(-50%);transform:translateX(-50%)}.uagb-container__shape .uagb-container__shape-fill{-webkit-transform-origin:center;-ms-transform-origin:center;transform-origin:center;-webkit-transform:rotateY(0deg);transform:rotateY(0deg)}.uagb-container__shape.uagb-container__shape-above-content{z-index:9;pointer-events:none}.nv-single-page-wrap .nv-content-wrap.entry-content .wp-block-uagb-container.alignfull{margin-left:calc(50% - 50vw);margin-right:calc(50% - 50vw)}@media only screen and (max-width: 767px){.wp-block-uagb-container .wp-block-uagb-advanced-heading{width:-webkit-fill-available}}.wp-block-uagb-image--align-none{justify-content:center}.wp-block-uagb-container.uagb-block-ddf22a51 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-ddf22a51 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-ddf22a51 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-ddf22a51 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-ddf22a51 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-ddf22a51{max-width: 21%;width: 100%;}.wp-block-uagb-container.uagb-block-ddf22a51{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: auto;order: initial;border-color: inherit;flex-direction: row;align-items: center;justify-content: flex-start;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-ddf22a51.wp-block-uagb-container > *:not( .wp-block-uagb-column ):not( .wp-block-uagb-section ):not( .uagb-container__shape ):not( .uagb-container__video-wrap ):not( .uagb-slider-container ):not( .spectra-container-link-overlay ):not(.spectra-image-gallery__control-lightbox):not(.wp-block-uagb-lottie):not(.uagb-container-inner-blocks-wrap){width: auto !important;}.wp-block-uagb-container.uagb-block-ddf22a51.wp-block-uagb-container > .uagb-container-inner-blocks-wrap > *:not( .wp-block-uagb-column ):not( .wp-block-uagb-section ):not( .uagb-container__shape ):not( .uagb-container__video-wrap ):not( .uagb-slider-container ):not(.spectra-image-gallery__control-lightbox){width: auto !important;}.wp-block-uagb-container.uagb-block-f3951781 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-f3951781 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-f3951781 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-f3951781 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-f3951781 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-f3951781{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-block-f3951781{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;max-width: 100% !important;width: 100%;}.uagb-block-d068befa.wp-block-uagb-image{margin-top: 0px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;}.uagb-block-d068befa.wp-block-uagb-image--layout-default figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-d068befa.wp-block-uagb-image .wp-block-uagb-image__figure figcaption{font-style: normal;align-self: center;}.uagb-block-d068befa.wp-block-uagb-image--layout-overlay figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-d068befa.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 0.2;}.uagb-block-d068befa.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner{left: 15px;right: 15px;top: 15px;bottom: 15px;}.uagb-block-d068befa.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading{font-style: normal;color: #fff;opacity: 1;}.uagb-block-d068befa.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading a{color: #fff;}.uagb-block-d068befa.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 0;}.uagb-block-d068befa.wp-block-uagb-image--layout-overlay .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 1;}.uagb-block-d068befa.wp-block-uagb-image .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{width: 30%;border-top-width: 2px;border-top-color: #fff;opacity: 0;}.uagb-block-d068befa.wp-block-uagb-image .wp-block-uagb-image__figure img{object-fit: contain;width: 71px;height: 50px;}.uagb-block-d068befa.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 1;}.uagb-block-d068befa.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{opacity: 1;}.wp-block-uagb-container.uagb-block-7e42bba6 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-7e42bba6 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-7e42bba6 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-7e42bba6 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-7e42bba6 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-7e42bba6{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-block-7e42bba6{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;max-width: 100% !important;width: 100%;}.wp-block-uagb-advanced-heading.uagb-block-a545db33.wp-block-uagb-advanced-heading {margin-top: 0px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.wp-block-uagb-advanced-heading.uagb-block-a545db33.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-a545db33.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-a545db33.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-a545db33.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-a545db33 .uagb-heading-text{line-height: 1.2em;}@media only screen and (max-width: 976px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-ddf22a51{width: 100%;}.wp-block-uagb-container.uagb-block-ddf22a51{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-direction: row;align-items: center;}.wp-block-uagb-container.uagb-block-ddf22a51.wp-block-uagb-container > *:not( .wp-block-uagb-column ):not( .wp-block-uagb-section ):not( .uagb-container__shape ):not( .uagb-container__video-wrap ):not( .uagb-slider-container ):not( .spectra-container-link-overlay ):not(.spectra-image-gallery__control-lightbox):not(.wp-block-uagb-lottie):not(.uagb-container-inner-blocks-wrap){width: 100%;}.wp-block-uagb-container.uagb-block-ddf22a51.wp-block-uagb-container > .uagb-container-inner-blocks-wrap > *:not( .wp-block-uagb-column ):not( .wp-block-uagb-section ):not( .uagb-container__shape ):not( .uagb-container__video-wrap ):not( .uagb-slider-container ):not(.spectra-image-gallery__control-lightbox){width: 100%;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-f3951781{width: 100%;}.wp-block-uagb-container.uagb-block-f3951781{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;max-width:  !important;}.uagb-block-d068befa.wp-block-uagb-image .wp-block-uagb-image__figure img{object-fit: contain;width: 71px;height: 50px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-7e42bba6{width: 100%;}.wp-block-uagb-container.uagb-block-7e42bba6{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;max-width:  !important;}.wp-block-uagb-advanced-heading.uagb-block-a545db33.wp-block-uagb-advanced-heading {text-align: left;padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;margin-top: 0px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;}.wp-block-uagb-advanced-heading.uagb-block-a545db33 .uagb-heading-text{font-size: 30px;line-height: 0em;}}@media only screen and (max-width: 767px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-ddf22a51{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-block-ddf22a51{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-direction: row;align-items: center;justify-content: center;flex-wrap: nowrap;}.wp-block-uagb-container.uagb-block-ddf22a51.wp-block-uagb-container > *:not( .wp-block-uagb-column ):not( .wp-block-uagb-section ):not( .uagb-container__shape ):not( .uagb-container__video-wrap ):not( .uagb-slider-container ):not( .spectra-container-link-overlay ):not(.spectra-image-gallery__control-lightbox):not(.wp-block-uagb-lottie):not(.uagb-container-inner-blocks-wrap){width: auto !important;}.wp-block-uagb-container.uagb-block-ddf22a51.wp-block-uagb-container > .uagb-container-inner-blocks-wrap > *:not( .wp-block-uagb-column ):not( .wp-block-uagb-section ):not( .uagb-container__shape ):not( .uagb-container__video-wrap ):not( .uagb-slider-container ):not(.spectra-image-gallery__control-lightbox){width: auto !important;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-f3951781{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-block-f3951781{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;max-width: 100% !important;}.uagb-block-d068befa.wp-block-uagb-image .wp-block-uagb-image__figure img{object-fit: contain;width: 57px;height: 50px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-7e42bba6{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-block-7e42bba6{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;max-width: 100% !important;}.wp-block-uagb-advanced-heading.uagb-block-a545db33.wp-block-uagb-advanced-heading {text-align: center;padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;margin-top: 0px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;}.wp-block-uagb-advanced-heading.uagb-block-a545db33.wp-block-uagb-advanced-heading .uagb-highlight{padding-bottom: 0px;}.wp-block-uagb-advanced-heading.uagb-block-a545db33 .uagb-heading-text{font-size: 24px;}}\";s:2:\"js\";s:0:\"\";s:18:\"current_block_list\";a:34:{i:0;s:11:\"core\/search\";i:1;s:10:\"core\/group\";i:2;s:12:\"core\/heading\";i:3;s:17:\"core\/latest-posts\";i:4;s:20:\"core\/latest-comments\";i:5;s:13:\"core\/archives\";i:6;s:15:\"core\/categories\";i:7;s:18:\"core\/legacy-widget\";i:8;s:24:\"woocommerce\/price-filter\";i:9;s:17:\"core\/widget-group\";i:10;s:27:\"woocommerce\/product-on-sale\";i:11;s:18:\"uagb\/taxonomy-list\";i:12;s:13:\"uagb\/info-box\";i:13;s:30:\"woocommerce\/product-categories\";i:14;s:27:\"woocommerce\/product-filters\";i:15;s:33:\"woocommerce\/product-filter-rating\";i:16;s:40:\"woocommerce\/product-filter-checkbox-list\";i:17;s:33:\"woocommerce\/product-filter-active\";i:18;s:42:\"woocommerce\/product-filter-removable-chips\";i:19;s:39:\"woocommerce\/product-filter-clear-button\";i:20;s:12:\"core\/buttons\";i:21;s:11:\"core\/button\";i:22;s:32:\"woocommerce\/product-filter-price\";i:23;s:39:\"woocommerce\/product-filter-price-slider\";i:24;s:36:\"woocommerce\/product-filter-attribute\";i:25;s:33:\"woocommerce\/product-filter-status\";i:26;s:34:\"yith\/yith-wcan-ajax-filters-preset\";i:27;s:14:\"core\/paragraph\";i:28;s:21:\"uagb\/advanced-heading\";i:29;s:14:\"uagb\/separator\";i:30;s:10:\"uagb\/image\";i:31;s:14:\"uagb\/container\";i:32;s:14:\"core\/shortcode\";i:33;s:9:\"srfm\/form\";}s:8:\"uag_flag\";b:1;s:11:\"uag_version\";s:10:\"1788377293\";s:6:\"gfonts\";a:0:{}s:10:\"gfonts_url\";s:0:\"\";s:12:\"gfonts_files\";a:0:{}s:14:\"uag_faq_layout\";b:0;}"]},"uagb_featured_image_src":{"full":["https:\/\/www.wincocentury.com\/wp-content\/uploads\/2026\/02\/Russell-Hobbs-RH-22550-56-01.webp",1000,1000,false],"thumbnail":["https:\/\/www.wincocentury.com\/wp-content\/uploads\/2026\/02\/Russell-Hobbs-RH-22550-56-01-150x150.webp",150,150,true],"medium":["https:\/\/www.wincocentury.com\/wp-content\/uploads\/2026\/02\/Russell-Hobbs-RH-22550-56-01-300x300.webp",300,300,true],"medium_large":["https:\/\/www.wincocentury.com\/wp-content\/uploads\/2026\/02\/Russell-Hobbs-RH-22550-56-01-768x768.webp",768,768,true],"large":["https:\/\/www.wincocentury.com\/wp-content\/uploads\/2026\/02\/Russell-Hobbs-RH-22550-56-01.webp",1000,1000,false],"1536x1536":["https:\/\/www.wincocentury.com\/wp-content\/uploads\/2026\/02\/Russell-Hobbs-RH-22550-56-01.webp",1000,1000,false],"2048x2048":["https:\/\/www.wincocentury.com\/wp-content\/uploads\/2026\/02\/Russell-Hobbs-RH-22550-56-01.webp",1000,1000,false],"trp-custom-language-flag":["https:\/\/www.wincocentury.com\/wp-content\/uploads\/2026\/02\/Russell-Hobbs-RH-22550-56-01-12x12.webp",12,12,true],"woocommerce_thumbnail":["https:\/\/www.wincocentury.com\/wp-content\/uploads\/2026\/02\/Russell-Hobbs-RH-22550-56-01-300x300.webp",300,300,true],"woocommerce_single":["https:\/\/www.wincocentury.com\/wp-content\/uploads\/2026\/02\/Russell-Hobbs-RH-22550-56-01-600x600.webp",600,600,true],"woocommerce_gallery_thumbnail":["https:\/\/www.wincocentury.com\/wp-content\/uploads\/2026\/02\/Russell-Hobbs-RH-22550-56-01-100x100.webp",100,100,true]},"uagb_author_info":{"display_name":"wincocenturylimited@gmail.com","author_link":"https:\/\/www.wincocentury.com\/en\/author\/"},"uagb_comment_info":0,"uagb_excerpt":"\u53ef\u62c6\u5378\u6d17\u7897\u6a5f\u5b89\u5168\u70e4\u76e4 \u4e0d\u7c98\u5857\u5c64 \u4f7f\u7528\u548c\u64cd\u4f5c\u7c21\u55ae \u5d4c\u5165\u5f0f\u52a0\u71b1\u5143\u4ef6 \u5feb\u901f\u52a0\u71b1 \u53ef\u8abf\u7bc0\u6eab\u5ea6\u63a7\u5236 \u53ef\u62c6\u5378\u96fb\u7e9c\u548c\u6ef4\u6c34\u76e4","_links":{"self":[{"href":"https:\/\/www.wincocentury.com\/en\/wp-json\/wp\/v2\/product\/12264","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.wincocentury.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.wincocentury.com\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.wincocentury.com\/en\/wp-json\/wp\/v2\/media\/12091"}],"wp:attachment":[{"href":"https:\/\/www.wincocentury.com\/en\/wp-json\/wp\/v2\/media?parent=12264"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.wincocentury.com\/en\/wp-json\/wp\/v2\/product_brand?post=12264"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.wincocentury.com\/en\/wp-json\/wp\/v2\/product_cat?post=12264"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.wincocentury.com\/en\/wp-json\/wp\/v2\/product_tag?post=12264"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}